{"id":7866,"date":"2022-12-01T05:08:21","date_gmt":"2022-12-01T04:08:21","guid":{"rendered":"https:\/\/fortalezadeocastro.vigo.org\/o-monte-de-o-castro\/"},"modified":"2024-02-03T12:26:57","modified_gmt":"2024-02-03T11:26:57","slug":"o-monte-de-o-castro","status":"publish","type":"page","link":"https:\/\/fortalezadeocastro.vigo.org\/en\/o-monte-de-o-castro\/","title":{"rendered":"O monte de O Castro"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7866\" class=\"elementor elementor-7866 elementor-6667\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f2c9d8 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f2c9d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbe3b2c\" data-id=\"fbe3b2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1990390 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1990390\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O monte de O Castro<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c9275a elementor-widget elementor-widget-heading\" data-id=\"0c9275a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">A defensa de Vigo<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4850164 elementor-section-stretched gt-history-home-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4850164\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e30b27a\" data-id=\"e30b27a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-53b3121 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"53b3121\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf3bbf8\" data-id=\"cf3bbf8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e48541 elementor-widget elementor-widget-heading\" data-id=\"8e48541\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">imaxe cabeceira<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e7f0e8 elementor-widget elementor-widget-text-editor\" data-id=\"6e7f0e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>O monte de O Castro en diferentes vistas na 1\u00ba metade do s\u00e9culo XX. Arquivo Pacheco <br \/><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cfab5aa\" data-id=\"cfab5aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c101259 elementor-widget elementor-widget-heading\" data-id=\"c101259\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">O Monte do Castro \u00e9 quizais un dos lugares que m\u00e1is identifica \u00e1 nosa cidade pola s\u00faas especias caracter\u00edsticas xeogr\u00e1ficas e hist\u00f3ricas.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bb6b5f elementor-widget elementor-widget-text-editor\" data-id=\"9bb6b5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Xunto ao Parque de Castrelos, \u00e9 a principal zona verde do casco urbano, cun papel clave dende o punto de vista medioambiental. Pero tam\u00e9n \u00e9 lugar de ocio e esparexemento e un lugar con moitos referentes asociados \u00e1 nosa historia e arte, reflectidos nos restos arqueol\u00f3xicos de \u00e9poca castrexa, o castelo do s\u00e9culo XVII ou as diferentes esculturas que poban todo o monte.<\/p><p>Este monte xunto co o da Gu\u00eda, son dous excelentes miradoiros que nos permiten ter unha panor\u00e1mica sobre a cidade constru\u00edda \u00e1 beira da r\u00eda, \u00e1mbalas d\u00faas, compa\u00f1eiras de viaxe na conformaci\u00f3n da primeira cidade de Galicia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e1323 elementor-widget elementor-widget-loquet-image-gallery-widget\" data-id=\"27e1323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"loquet-image-gallery-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gt-image-gallery gt-style-1\"><div class=\"swiper gt-carousel-container\" data-gt-item=\"1\" data-gt-item-group=\"1\" data-gt-item-space=\"0\" data-gt-loop=\"false\" data-gt-speed=\"1500\" data-gt-centered-slides=\"false\" data-gt-direction=\"horizontal\" data-gt-effect=\"slide\" data-gt-free-mode=\"false\" data-gt-lazy-loading=\"true\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750.jpg 1772w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-600x414.jpg 600w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-300x207.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-1024x706.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-768x530.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-1536x1059.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-415x286.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-650x448.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-250x172.jpg 250w\" data-caption=\"O monte de O Castro en diferentes vistas na 1\u00ba metade do s\u00e9culo XX. Arquivo fotofr\u00e1fico Pacheco, Concello de Vigo\"><\/a><div class=\"gt-details\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"feather feather-maximize\"><path d=\"M8 3H5a2 2 0 0 0-2 2v3m18 0V5a2 2 0 0 0-2-2h-3m0 18h3a2 2 0 0 0 2-2v-3M3 16v3a2 2 0 0 0 2 2h3\"><\/path><\/svg><span>O monte de O Castro en diferentes vistas na 1\u00ba metade do s\u00e9culo XX. Arquivo fotofr\u00e1fico Pacheco, Concello de Vigo<\/span><\/div><img fetchpriority=\"high\" decoding=\"async\" width=\"1772\" height=\"1222\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750.jpg\" class=\"attachment-full size-full\" alt=\"O monte de O Castro en diferentes vistas na 1\u00ba metade do s\u00e9culo XX. Arquivo fotofr\u00e1fico Pacheco, Concello de Vigo\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750.jpg 1772w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-600x414.jpg 600w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-300x207.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-1024x706.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-768x530.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-1536x1059.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-415x286.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-650x448.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2022\/11\/01_02750-250x172.jpg 250w\" sizes=\"(max-width: 1772px) 100vw, 1772px\" \/><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e102ed elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1e102ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8596bfa\" data-id=\"8596bfa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f04a52 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9f04a52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">As ladeiras do monte de O Castro acolleron un dos asentamentos amurallados m\u00e1is poboados e din\u00e1micos do territorio galaico<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ce6e909 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ce6e909\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-89c8652\" data-id=\"89c8652\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a076e68\" data-id=\"a076e68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41d8fb9 elementor-widget elementor-widget-heading\" data-id=\"41d8fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A cidade<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1cab06 elementor-widget elementor-widget-text-editor\" data-id=\"e1cab06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A finais do s\u00e9culo XIX, o desenvolvemento econ\u00f3mico xurdido a partir da creaci\u00f3n de industrias derivadas do mar vai ser clave na nova configuraci\u00f3n da cidade de Vigo. O crecemento do sector pesqueiro plasmarase na aparici\u00f3n de novas t\u00e9cnicas de conserva do peixe, o emprego da m\u00e1quina de vapor nas embarcaci\u00f3ns pesqueiras, as novas artes de pesca, e por fin a chegada do ferrocarril a Vigo.<\/p><p>O desenvolvemento econ\u00f3mico vigu\u00e9s estivo as\u00ed ata mediados do s\u00e9culo XX directamente relacionado co mar: da man dunha burgues\u00eda din\u00e1mica e emprendedora, procedente na s\u00faa maior parte do Pa\u00eds Vasco e Catalu\u00f1a, xurde o primeiro sector industrial galego, a industria conserveira, orientada nun primeiro momento cara ao comercio exterior. Arredor da conserva desenvolv\u00e9ronse unha gran cantidade de industrias auxiliares (cordoar\u00eda, xeo, naval, litograf\u00eda, etc) o que provocou o auxe dos principais estaleiros vigueses. Vigo \u00eda concentrando as\u00ed a maior parte da industria e do comercio relacionado coa conserva e a pesca, polo que se converteu no principal pulm\u00f3n industrial de Galicia.<\/p><p>Ser\u00e1 neste contexto cando Vigo experimente unha importante transformaci\u00f3n dende a segunda metade do s\u00e9culo XIX, froito do auxe pesqueiro, comercial, industrial, demogr\u00e1fico e cultural, que levar\u00e1 a demoler as murallas a partir de 1861, e a comezar unha din\u00e1mica de crecemento ao longo das principais v\u00edas de comunicaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aa29502 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"aa29502\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7f46eb9\" data-id=\"7f46eb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2c312d elementor-widget elementor-widget-image\" data-id=\"c2c312d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Plano de la Ciudad de Vigo 1982 - Manuel F. Soler\" data-elementor-lightbox-description=\"Plano de la Ciudad de Vigo 1982 - Manuel F. Soler\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzgyNiwidXJsIjoiaHR0cHM6XC9cL2ZvcnRhbGV6YWRlb2Nhc3Ryby52aWdvLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDJcLzAxX01hbnVlbF9GX1NvbGVyX1BsYW5vX1ZpZ29fMTk4My1zY2FsZWQuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1445\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-scaled.jpg\" class=\"attachment-full size-full wp-image-7826\" alt=\"\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-300x169.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-1024x578.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-768x434.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-1536x867.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-2048x1156.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-415x234.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-650x367.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-250x141.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-600x339.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ac096e4\" data-id=\"ac096e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ca8c9a elementor-widget elementor-widget-heading\" data-id=\"4ca8c9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Urz\u00e1iz, Policarpo Sanz e Col\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e88d2e elementor-widget elementor-widget-heading\" data-id=\"5e88d2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Un cat\u00e1logo de arquitectura<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-453290c elementor-widget elementor-widget-text-editor\" data-id=\"453290c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Derrubados os vellos muros, a cidade comezar\u00e1 a s\u00faa expansi\u00f3n en torno a unha serie de eixos lonxitudinais pola r\u00faa do Pr\u00edncipe, r\u00faa da Circunvalaci\u00f3n (hoxe Policarpo Sanz), r\u00faa do Ramal (hoxe Col\u00f3n), r\u00faa do Cami\u00f1o a Estaci\u00f3n (hoxe Urzaiz), onde establecer\u00e1n a s\u00faa residencia esa burgues\u00eda industrial do momento.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-16144c2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"16144c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37db35a\" data-id=\"37db35a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dd294b elementor-widget elementor-widget-heading\" data-id=\"2dd294b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Plano da CIDADE DE VIGO<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bfefe5 elementor-widget elementor-widget-text-editor\" data-id=\"5bfefe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 14px;\">1982 \u2013 Manuel F. Soler<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8c60c62\" data-id=\"8c60c62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cabb697 elementor-widget elementor-widget-text-editor\" data-id=\"cabb697\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ao derrubarse a Porta do Sol en 1869 comeza un proxecto ambicioso de conectar a estrada de Castela coa estrada de Baiona a trav\u00e9s da Traves\u00eda de Vigo (hoxe Elduayen). Este proxecto no que se investiron m\u00e1is de vinte anos supuxo o derrubamento de varias edificaci\u00f3ns, entre elas a Capela da Misericordia (s. XVI), e dividiu o centro hist\u00f3rico en dous barrios, o barrio alto e o barrio baixo que condenou \u00e1 degradaci\u00f3n ao primeiro.<\/p><p><span style=\"font-size: inherit;\">O crecemento urbano cara ao eixo Porta do Sol, Col\u00f3n e Urz\u00e1iz, nun primeiro momento, levou consigo a construci\u00f3n de edificios representativos da nosa cidade. A pesar de que hoxe en d\u00eda perderon os seus usos e funci\u00f3ns orixinarias estes edificios contin\u00faan sendo representativos do per\u00edodo de esplendor da cidade (o Edificio Sime\u00f3n, a Casa Pardo Labarta ou o Gran Hotel Moderno).<\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a603667 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a603667\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-aeec831\" data-id=\"aeec831\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c78c005 elementor-widget elementor-widget-loquet-image-gallery-widget\" data-id=\"c78c005\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"loquet-image-gallery-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gt-image-gallery gt-style-1\"><div class=\"swiper gt-carousel-container\" data-gt-item=\"1\" data-gt-item-group=\"1\" data-gt-item-space=\"0\" data-gt-loop=\"false\" data-gt-speed=\"1500\" data-gt-centered-slides=\"false\" data-gt-direction=\"horizontal\" data-gt-effect=\"slide\" data-gt-free-mode=\"false\" data-gt-lazy-loading=\"true\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-scaled.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-300x139.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-1024x473.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-768x355.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-1536x709.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-2048x946.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-415x192.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-650x300.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-250x115.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-600x277.jpg 600w\" data-caption=\"Porta do Sol en 1897. Apertura da r\u00faa Elduayen\"><\/a><div class=\"gt-details\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"feather feather-maximize\"><path d=\"M8 3H5a2 2 0 0 0-2 2v3m18 0V5a2 2 0 0 0-2-2h-3m0 18h3a2 2 0 0 0 2-2v-3M3 16v3a2 2 0 0 0 2 2h3\"><\/path><\/svg><span>Porta do Sol en 1897. Apertura da r\u00faa Elduayen<\/span><\/div><img decoding=\"async\" width=\"2560\" height=\"1182\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-300x139.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-1024x473.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-768x355.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-1536x709.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-2048x946.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-415x192.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-650x300.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-250x115.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/02_Porta_do_Sol_1897_Apertura_da_rua-Elduayen_Jenaro_de_la_fuente-600x277.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-21d1b4e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"21d1b4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-758a18f\" data-id=\"758a18f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6798da elementor-widget elementor-widget-heading\" data-id=\"b6798da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">PLANO<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aae6889 elementor-widget elementor-widget-text-editor\" data-id=\"aae6889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Porta do Sol en 1897. Apertura da r\u00faa Elduayen -Dese\u00f1o Jenaro de la Fuente<\/p><p><br><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e415686\" data-id=\"e415686\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bc1abf elementor-widget elementor-widget-text-editor\" data-id=\"8bc1abf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Paralelamente a isto levouse a cabo no \u00faltimo terzo do XIX a gran obra de recheos ga\u00f1ados ao mar e a construci\u00f3n do peirao de madeira.<\/p><p>D\u00faas datas clave para a nosa cidade son 1904, na que se produce a anexi\u00f3n do municipio lim\u00edtrofe de Bouzas e 1941, na que se anexiona o concello de Lavadores. O primeiro deles, de gran tradici\u00f3n ligada ao mar, conserva a s\u00faa propia identidade nos nosos d\u00edas. Lavadores a\u00ednda que inclu\u00eda a franxa mar\u00edtima da parroquia de Teis sustent\u00e1base maiormente na produci\u00f3n agr\u00edcola e gandeira.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2aaddf elementor-widget elementor-widget-heading\" data-id=\"c2aaddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A vila aberta ao mar.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b35d02 elementor-widget elementor-widget-heading\" data-id=\"8b35d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Planificaci\u00f3n do crecemento.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00520c2 elementor-widget elementor-widget-text-editor\" data-id=\"00520c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">O crecemento experimentado pola vila dende finais do XVIII creou a necesidade dun proxecto de planificaci\u00f3n da Nova Poboaci\u00f3n para <\/span><span style=\"font-weight: 400;\">substitu\u00edr <\/span><span style=\"font-weight: 400;\">unha vella cidade amurallada, insuficiente e inadecuada \u00e1s novas demandas de chan. A ampliaci\u00f3n da cidade non vai ser an\u00e1rquica, xa que dende dos organismos oficiais tratarase dende datas moi temper\u00e1s de planificar ese crecemento urbano a trav\u00e9s de leis de ensanche, leis de saneamento e abastecemento de auga, ordenanzas <\/span><span style=\"font-weight: 400;\">municipais e dunha serie de proxectos de ensanche.<\/span><\/p><p><span style=\"font-weight: 400;\">En moi poucos casos estes proxectos chegar\u00e1n a propo\u00f1er unha remodelaci\u00f3n integral que incl\u00faa o centro hist\u00f3rico, entre eles o Plan Palacios de 1932. En dito plan pl\u00e1ntease por vez primeira a idea de zonificar, \u00e9 dicir, distribu\u00edr de xeito l\u00f3xico en \u00e1reas os diferentes usos residenciais, administrativos, industriais, etc.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f95ca4 elementor-widget elementor-widget-loquet-image-gallery-widget\" data-id=\"6f95ca4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"loquet-image-gallery-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gt-image-gallery gt-style-3\"><div class=\"swiper gt-carousel-container\" data-gt-item=\"1\" data-gt-item-group=\"1\" data-gt-item-space=\"0\" data-gt-loop=\"false\" data-gt-speed=\"1500\" data-gt-centered-slides=\"false\" data-gt-direction=\"horizontal\" data-gt-effect=\"slide\" data-gt-free-mode=\"false\" data-gt-lazy-loading=\"true\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios.jpg 640w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios-300x216.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios-415x298.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios-250x180.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios-600x431.jpg 600w\" data-caption=\"Plan urban\u00edstico de Antonio Palacios, 1932\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"460\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios.jpg\" class=\"attachment-full size-full\" alt=\"Plan urban\u00edstico de Antonio Palacios, 1932\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios.jpg 640w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios-300x216.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios-415x298.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios-250x180.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/vigopalacios-600x431.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/div><div class=\"gt-details\"><span>Plan urban\u00edstico de Antonio Palacios, 1932<\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9f3619 elementor-widget elementor-widget-text-editor\" data-id=\"d9f3619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Estas propostas na maior parte dos casos non chegar\u00e1n a executarse debido a acontecementos pol\u00edticos e principalmente \u00e1 oposici\u00f3n de certos sectores socio-econ\u00f3micos (comerciantes, industriais) que se opuxeron a esta planificaci\u00f3n, debido a que viron perigar os seus intereses.<\/span><\/p><p><span style=\"font-weight: 400;\">Os datos cos que contamos na actualidade po\u00f1en de manifesto que Vigo foi unha das primeiras cidades espa\u00f1olas en tentar levar \u00e1 pr\u00e1ctica unha concepci\u00f3n planificada do crecemento urbano, adiant\u00e1ndose aos proxectos que dende mediados do XIX se <\/span><span style=\"font-weight: 400;\">comezar\u00edan<\/span><span style=\"font-weight: 400;\"> a utilizar nas principais cidades europeas e espa\u00f1olas.<\/span><\/p><p><span style=\"font-weight: 400;\">O primeiro proxecto de autor desco\u00f1ecido data de 1807, no que proxectaba un novo peirao xunto \u00e1 ampliaci\u00f3n de terreos edificables e a prolongaci\u00f3n das murallas. Sobre este vai traballar o enxe\u00f1eiro militar Jos\u00e9 M\u00fcller situando a nova poboaci\u00f3n o leste do recinto amurallado, sobre a praia do Areal. O plano de M\u00fcller, vai ser continuado polo enxe\u00f1eiro Carlos M\u00aa Abajos, que o modificou en parte.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-67a28f7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"67a28f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-42aa281\" data-id=\"42aa281\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1355521 elementor-widget elementor-widget-loquet-image-gallery-widget\" data-id=\"1355521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"loquet-image-gallery-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gt-image-gallery gt-style-4\"><div class=\"swiper gt-carousel-container\" data-gt-item=\"1\" data-gt-item-group=\"1\" data-gt-item-space=\"0\" data-gt-loop=\"false\" data-gt-speed=\"1500\" data-gt-centered-slides=\"false\" data-gt-direction=\"horizontal\" data-gt-effect=\"slide\" data-gt-free-mode=\"false\" data-gt-lazy-loading=\"true\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-scaled.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-300x171.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-1024x582.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-768x437.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-1536x873.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-2048x1164.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-415x236.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-650x370.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-250x142.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-600x341.jpg 600w\" data-caption=\"Plan de ensanche de M\u00fcller, 1807\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1455\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Plan de ensanche de M\u00fcller, 1807\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-300x171.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-1024x582.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-768x437.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-1536x873.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-2048x1164.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-415x236.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-650x370.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-250x142.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_muller-600x341.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><div class=\"gt-details\"><span>Plan de ensanche de M\u00fcller, 1807<\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf160a5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cf160a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78c9e09\" data-id=\"78c9e09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cb23bb elementor-widget elementor-widget-heading\" data-id=\"7cb23bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">PLANO<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bbb0b2 elementor-widget elementor-widget-text-editor\" data-id=\"9bbb0b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Proxecto para a situaci\u00f3n dun peirao na R\u00eda e fondeadoiro de Vigo. con proporcionada nova Aduana. competente aumento de poboaci\u00f3n suficiente seguridade de defensas para rexeitar un golpe de man por esta parte e todas as demais vantaxes que require o ben desexado fomento do seu comercio<br \/>.<br \/>M\u00fcller, 1807<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c5b8375\" data-id=\"c5b8375\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4764b5 elementor-widget elementor-widget-heading\" data-id=\"c4764b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">O ensanche de nova poboaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c829d63 elementor-widget elementor-widget-heading\" data-id=\"c829d63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Plan de Agust\u00edn de Marcoart\u00fa. 1825<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de62136 elementor-widget elementor-widget-text-editor\" data-id=\"de62136\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Tras eses primeiros intentos de ampliaci\u00f3n da cidade, que se sucederon a principios do XIX, a finais da d\u00e9cada de 1830, e retomada a idea de ensanche da cidade, enc\u00e1rgase un novo proxecto ao enxe\u00f1eiro Agust\u00edn de Marcoart\u00fa, quen rexeita o plano de M\u00fcller e presenta un plano novidoso, m\u00e1is adecuado \u00e1s novas necesidades. Nel form\u00falase o crecemento da cidade cara o leste do recinto amurallado, na zona da praia do Areal, en parte sobre terreos ga\u00f1ados ao mar. Tr\u00e1tase dunha proposta totalizante da nova cidade a constru\u00edr, non entend\u00e9ndose <\/span><span style=\"font-weight: 400;\">unicamente <\/span><span style=\"font-weight: 400;\">como unha mera ampliaci\u00f3n da cidade existente, <\/span><span style=\"font-weight: 400;\">ademais <\/span><span style=\"font-weight: 400;\">plantexa un concepto de urbanismo sustentado na existencia e desenvolvemento do porto.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a8708c elementor-widget elementor-widget-loquet-image-gallery-widget\" data-id=\"5a8708c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"loquet-image-gallery-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gt-image-gallery gt-style-4\"><div class=\"swiper gt-carousel-container\" data-gt-item=\"1\" data-gt-item-group=\"1\" data-gt-item-space=\"0\" data-gt-loop=\"false\" data-gt-speed=\"1500\" data-gt-centered-slides=\"false\" data-gt-direction=\"horizontal\" data-gt-effect=\"slide\" data-gt-free-mode=\"false\" data-gt-lazy-loading=\"true\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo.jpg 2454w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-300x226.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-1024x773.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-768x580.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-1536x1159.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-2048x1546.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-415x313.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-650x491.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-250x189.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-600x453.jpg 600w\" data-caption=\"Proxecto dun Peirao de Comercio e Pesca, no Porto de Vigo, cun plan xeral dunha nova poboaci\u00f3n que determine o lugar que debe ocupar cada Edificio particular e p\u00fablico map: para que co tempo resulta unha Cidade grande, fermosa, sim\u00e9trica e colocada cada oficina no sitio mais \u00e1 mantenta para a convenci\u00f3n de todos os seus habitantes; coas s\u00faas bater\u00edas que a po\u00f1an a cuberto dos insultos da mar. Servicio Geogr\u00e1fico del Ej\u00e9rcito - 1851\"><img loading=\"lazy\" decoding=\"async\" width=\"2454\" height=\"1852\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo.jpg\" class=\"attachment-full size-full\" alt=\"Proxecto dun Peirao de Comercio e Pesca, no Porto de Vigo, cun plan xeral dunha nova poboaci\u00f3n que determine o lugar que debe ocupar cada Edificio particular e p\u00fablico map: para que co tempo resulta unha Cidade grande, fermosa, sim\u00e9trica e colocada cada oficina no sitio mais \u00e1 mantenta para a convenci\u00f3n de todos os seus habitantes; coas s\u00faas bater\u00edas que a po\u00f1an a cuberto dos insultos da mar. Servicio Geogr\u00e1fico del Ej\u00e9rcito - 1851\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo.jpg 2454w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-300x226.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-1024x773.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-768x580.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-1536x1159.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-2048x1546.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-415x313.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-650x491.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-250x189.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/03_proxecto_muelle_comercio_vigo-600x453.jpg 600w\" sizes=\"(max-width: 2454px) 100vw, 2454px\" \/><\/a><\/div><div class=\"gt-details\"><span>Proxecto dun Peirao de Comercio e Pesca, no Porto de Vigo, cun plan xeral dunha nova poboaci\u00f3n que determine o lugar que debe ocupar cada Edificio particular e p\u00fablico map: para que co tempo resulta unha Cidade grande, fermosa, sim\u00e9trica e colocada cada oficina no sitio mais \u00e1 mantenta para a convenci\u00f3n de todos os seus habitantes; coas s\u00faas bater\u00edas que a po\u00f1an a cuberto dos insultos da mar. Servicio Geogr\u00e1fico del Ej\u00e9rcito - 1851<\/span><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-scaled.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-300x201.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-1024x686.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-768x514.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-1536x1029.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-2048x1371.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-415x278.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-650x435.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-250x167.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-600x402.jpg 600w\" data-caption=\"Plano proyectado en el puerto de Vigo para sus muelles y nueva poblaci\u00f3n - \u00bfAgust\u00edn de Marcoart\u00fa?  - 18..\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1714\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Plano proyectado en el puerto de Vigo para sus muelles y nueva poblaci\u00f3n - \u00bfAgust\u00edn de Marcoart\u00fa? - 18..\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-300x201.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-1024x686.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-768x514.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-1536x1029.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-2048x1371.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-415x278.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-650x435.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-250x167.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/04_proxecto_muelle_comercio_vigo-600x402.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><div class=\"gt-details\"><span>Plano proyectado en el puerto de Vigo para sus muelles y nueva poblaci\u00f3n - \u00bfAgust\u00edn de Marcoart\u00fa?  - 18..<\/span><\/div><\/div><\/div><\/div><div class=\"gt-carousel-control gt-style-2 gt-light gt-position-bottom\"><div class=\"gt-carousel-navigation\"><div class=\"gt-carousel-prev\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 64\"><path d=\"M8.69 38.96c.38.38 1 .38 1.38 0 .38-.38.38-1 0-1.38l-5.49-5.47 5.49-5.49c.38-.38.38-1 0-1.38-.38-.38-1-.38-1.38 0l-6.16 6.09-.01.01c-.38.38-.37.99.01 1.37l6.16 6.25zm52.67-7.83H3.21v1.94h58.15v-1.94z\" fill=\"#020203\"><\/path><\/svg><\/div><div class=\"gt-carousel-next\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 64\"><path d=\"M61.07 32.72c.38-.38.38-.99.01-1.37l-.01-.01-6.16-6.09c-.38-.38-1-.38-1.38 0-.38.38-.38 1 0 1.38l5.49 5.49-5.49 5.47c-.38.38-.38 1 0 1.38.38.38 1 .38 1.38 0l6.16-6.25zm-58.83.34h58.15v-1.94H2.24v1.94z\" fill=\"#020203\"><\/path><\/svg><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9836993 elementor-widget elementor-widget-heading\" data-id=\"9836993\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Plan de Jose Mar\u00eda P\u00e9rez - \u00a01853<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f108b0 elementor-widget elementor-widget-text-editor\" data-id=\"4f108b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: inherit;\">En 1851 enc\u00e1rgaselle ao enxe\u00f1eiro Jos\u00e9 M\u00aa P\u00e9rez dar plasmaci\u00f3n real ao proxecto de Marcoart\u00fa, pero dadas as transformaci\u00f3ns experimentadas pola cidade co paso dos anos, vese obrigado a levar a cabo unha serie de modificaci\u00f3ns sobre o plano inicial de Marcoart\u00fa.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54a398a elementor-widget elementor-widget-loquet-image-gallery-widget\" data-id=\"54a398a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"loquet-image-gallery-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gt-image-gallery gt-style-3\"><div class=\"swiper gt-carousel-container\" data-gt-item=\"1\" data-gt-item-group=\"1\" data-gt-item-space=\"0\" data-gt-loop=\"false\" data-gt-speed=\"1500\" data-gt-centered-slides=\"false\" data-gt-direction=\"horizontal\" data-gt-effect=\"slide\" data-gt-free-mode=\"false\" data-gt-lazy-loading=\"true\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-scaled.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-300x184.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-1024x628.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-768x471.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-1536x941.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-2048x1255.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-415x254.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-650x398.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-250x153.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-600x368.jpg 600w\" data-caption=\"Plano General del puerto y playa de Vigo de sus muelles y nueva poblaci\u00f3n. 1853\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1569\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Plano General del puerto y playa de Vigo de sus muelles y nueva poblaci\u00f3n. 1853\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-300x184.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-1024x628.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-768x471.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-1536x941.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-2048x1255.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-415x254.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-650x398.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-250x153.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/05-plano_jm_perez-600x368.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><div class=\"gt-details\"><span>Plano General del puerto y playa de Vigo de sus muelles y nueva poblaci\u00f3n. 1853<\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-622d0d4 elementor-widget elementor-widget-heading\" data-id=\"622d0d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">O ensanche de Olloqui: Plans de Julio Vald\u00e9s\u00a01874-1876\u00a0\u00a0\u00a0\u00a0<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad17f93 elementor-widget elementor-widget-text-editor\" data-id=\"ad17f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tA pesar do interese que espertou este proxecto, tan s\u00f3 foi realizada unha pequena parte das obras contempladas no proxecto, correspondente \u00e1s tres primeiras fiadas de maz\u00e1s, que foron obxecto dunha concesi\u00f3n para a realizaci\u00f3n de obras a Emilio Garc\u00eda Olloqui en 1870. A concesi\u00f3n outorgada <\/span><span style=\"font-weight: 400;\">estend\u00edase <\/span><span style=\"font-weight: 400;\">ao leste do recinto amurallado sobre a zona do Areal ata a r\u00faa Ramal (hoxe Col\u00f3n). Pese \u00e1s grandes expectativas iniciais, o realmente edificado ser\u00edan apenas unhas poucas maz\u00e1s.<\/span><\/h5>\n<span style=\"font-weight: 400;\">O enxe\u00f1eiro Julio Vald\u00e9s \u00e9 o encargado de definir o ensanche <\/span><span style=\"font-weight: 400;\">concedido a Garc\u00eda Olloqui na parte m\u00e1is pr\u00f3xima ao Casco Vello. Estes planos xa trazan a actual r\u00faa Carral substitu\u00edndo a r\u00faa do Peirao e as v\u00edas paralelas ao mar Luis Taboada e a Praza de Compostela e as perpendiculares, Pablo Morillo, Col\u00f3n, Castelar e Garc\u00eda Olloqui.<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a187cb9 elementor-widget elementor-widget-loquet-image-gallery-widget\" data-id=\"a187cb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"loquet-image-gallery-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gt-image-gallery gt-style-3\"><div class=\"swiper gt-carousel-container\" data-gt-item=\"1\" data-gt-item-group=\"1\" data-gt-item-space=\"0\" data-gt-loop=\"false\" data-gt-speed=\"1500\" data-gt-centered-slides=\"false\" data-gt-direction=\"horizontal\" data-gt-effect=\"slide\" data-gt-free-mode=\"false\" data-gt-lazy-loading=\"true\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-scaled.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-300x206.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-1024x702.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-768x526.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-1536x1053.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-2048x1404.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-415x284.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-650x445.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-250x171.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-600x411.jpg 600w\" data-caption=\"Proxecto nova barriada para o porto de Vigo. Plano da nova barriada. Estudo Xeral de distribuci\u00f3n- 27 de maio 1874\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1754\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Proxecto nova barriada para o porto de Vigo. Plano da nova barriada. Estudo Xeral de distribuci\u00f3n- 27 de maio 1874\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-300x206.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-1024x702.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-768x526.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-1536x1053.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-2048x1404.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-415x284.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-650x445.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-250x171.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/06_Plano_garcia_olloqui-600x411.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><div class=\"gt-details\"><span>Proxecto nova barriada para o porto de Vigo. Plano da nova barriada. Estudo Xeral de distribuci\u00f3n- 27 de maio 1874<\/span><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-24b101f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"24b101f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fe53b71\" data-id=\"fe53b71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3640a17\" data-id=\"3640a17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3753b0e elementor-widget elementor-widget-heading\" data-id=\"3753b0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">PLAN XERAL DE MANUEL SOLER. 1883<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4bfa0c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a4bfa0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Manuel Soler traza no ano 1883 o primeiro \u201cPlan Xeral\u201d de Vigo. <\/span><span style=\"font-weight: 400;\">Este<\/span> <span style=\"font-weight: 400;\">xa \u00e9 un documento moderno no que se te\u00f1en en conta t\u00f3dalas preexistencias e tr\u00e1tase de encaixalas o mellor posible dentro dos novos trazados. O reto que afronta o proxectista \u00e9 arduo xa que t\u00f3dolos plans anteriores fracasaron porque fac\u00edan<\/span><span style=\"font-weight: 400;\"> t\u00e1boa <\/span><span style=\"font-weight: 400;\">rasa co anterior.<\/span><\/p><p><span style=\"font-weight: 400;\">Demostrando unha habilidade e unha capacidade de encaixe notable, o urbanista traza o que ser\u00e1n as maz\u00e1s do ensanche de Vigo dende a r\u00faa Venezuela ata o ensanche de Olloqui, chegando ata a conexi\u00f3n coa recentemente constru\u00edda estaci\u00f3n de tren. \u00c9 un plan <\/span><span style=\"font-weight: 400;\">de couzadas <\/span><span style=\"font-weight: 400;\">moderno que pasar\u00eda por actual no sentido en que ten en conta a topograf\u00eda e as v\u00edas que mellor se adaptaban a ela.<\/span><\/p><p><span style=\"font-weight: 400;\">Hai numerosos acertos como o trazado da circunvalaci\u00f3n do Casco Vello, hoxe Ronda de Don Bosco-Cachamu\u00ed\u00f1a, que permit\u00eda desviar o tr\u00e1fico da estradas de Pontevedra e Castela \u00e1 de Baiona sen pasar polo centro urbano (recordemos que a\u00ednda non exist\u00eda Elduayen). Na parte m\u00e1is sensible, o barrio do Areal, traza as r\u00faas de Marqu\u00e9s de Valladares e Rosal\u00eda de Castro e as s\u00faas perpendiculares que conectaban a estrada de circunvalaci\u00f3n co mar e que hoxe corresponden a Rep\u00fablica Arxentina, Canceleiro, Oporto\u2026<\/span><\/p><p><span style=\"font-weight: 400;\">Este trazado <\/span><span style=\"font-weight: 400;\">por fin convence \u00e1 cidadan\u00eda xa que fai un reparto proporcionado de cargas e beneficios e permite a execuci\u00f3n do desenvolvemento urbano. Por enriba de Policarpo Sanz tam\u00e9n acerta \u00f3 trazar a r\u00faa Uruguai, que continuaba paralela \u00e1 anterior ata Isaac Peral desgraciadamente interrompida <\/span><span style=\"font-weight: 400;\">hoxe en d\u00eda. Por \u00faltimo, entre Urz\u00e1iz e Venezuela prop\u00f3n en paralelo o eixo Mar\u00eda Berdiales-Progreso, ou perpendiculares como Hern\u00e1n Cort\u00e9s coa r\u00faa Cervantes.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3964d7 elementor-widget elementor-widget-image\" data-id=\"f3964d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Plano de la Ciudad de Vigo 1982 - Manuel F. Soler\" data-elementor-lightbox-description=\"Plano de la Ciudad de Vigo 1982 - Manuel F. Soler\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzgyNiwidXJsIjoiaHR0cHM6XC9cL2ZvcnRhbGV6YWRlb2Nhc3Ryby52aWdvLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDJcLzAxX01hbnVlbF9GX1NvbGVyX1BsYW5vX1ZpZ29fMTk4My1zY2FsZWQuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-1024x578.jpg\" class=\"attachment-large size-large wp-image-7826\" alt=\"\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-1024x578.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-300x169.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-768x434.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-1536x867.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-2048x1156.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-415x234.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-650x367.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-250x141.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/01_Manuel_F_Soler_Plano_Vigo_1983-600x339.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Plano de la Ciudad de Vigo 1982 - Manuel F. Soler<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2394112 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2394112\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cbf1837\" data-id=\"cbf1837\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6f90f34\" data-id=\"6f90f34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e9fcd3 elementor-widget elementor-widget-heading\" data-id=\"6e9fcd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">PLAN DE RAMIRO PASCUAL. 1907<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0042b10 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0042b10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ramiro Pascual contin\u00faa co bo planeamento anterior e trata de resolver os novos retos que afronta a cidade. En tan so 25 anos o ensanche de Soler est\u00e1 <\/span><span style=\"font-weight: 400;\">practicamente <\/span><span style=\"font-weight: 400;\">colmatado e \u00e9 preciso trazar os novos barrios.<\/span><\/p><p><span style=\"font-weight: 400;\">O urbanista acerta en pensar a expansi\u00f3n da cidade rodeando o Castro, cunha ret\u00edcula que se vai adaptando \u00e1 topograf\u00eda entorno a unha Gran V\u00eda que conectar\u00eda a estaci\u00f3n de tren co que hoxe co\u00f1ecemos como Praza de Am\u00e9rica. Na parte superior da r\u00faa Urz\u00e1iz dese\u00f1a o barrio de Casablanca, cunha cuadr\u00edcula perfecta e avenidas paralelas e perpendiculares \u00e1 pendente. As\u00ed vanse conformando as r\u00faas Gran V\u00eda, Cuba, M\u00e9xico, Brasil, V\u00e1zquez Varela.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-867f487 elementor-widget elementor-widget-image\" data-id=\"867f487\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Plan de Ramiro Pascual 1907\" data-elementor-lightbox-description=\"Plan de Ramiro Pascual 1907\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzg0NCwidXJsIjoiaHR0cHM6XC9cL2ZvcnRhbGV6YWRlb2Nhc3Ryby52aWdvLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDJcLzA3X1BsYW5vX1JhbWlyb19QYXNjdWFsLXNjYWxlZC5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"406\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-1024x406.jpg\" class=\"attachment-large size-large wp-image-7844\" alt=\"\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-1024x406.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-300x119.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-768x305.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-1536x609.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-2048x812.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-415x165.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-650x258.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-250x99.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/07_Plano_Ramiro_Pascual-600x238.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Plan de Ramiro Pascual 1907<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e3ffa39 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e3ffa39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a5e34d3\" data-id=\"a5e34d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41f517d\" data-id=\"41f517d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37f7180 elementor-widget elementor-widget-heading\" data-id=\"37f7180\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">PLAN DE MANUEL COMINGES. 1946<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f5e8ec elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6f5e8ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Xa mediado o s\u00e9culo XX e con parte do barrio de Casablanca constru\u00eddo, Cominges redefine partes fundamentais da cidade como o cruce da Gran V\u00eda coa baixada do Monte de O Castro nunha gran praza, hoxe de Espa\u00f1a. A maiores hai unha decisi\u00f3n crucial no tocante \u00f3s <\/span><span style=\"font-weight: 400;\">espazos verdes. Sendo consciente de que a Alameda quedara pequena coa expansi\u00f3n da cidade, proponse unha continuaci\u00f3n paralela \u00f3 mar ata o que hoxe co\u00f1ecemos como o n\u00f3 de Isaac Peral. Estes xard\u00edns cons\u00e9rvanse parcialmente hoxe en d\u00eda nun eixo verde dun quil\u00f3metro de longo que ser\u00eda desexable recuperar. Tam\u00e9n se detalla a continuaci\u00f3n <\/span><span style=\"font-weight: 400;\">de Marqu\u00e9s de Valladares e as intersecci\u00f3n coas v\u00edas perpendiculares nunha serie de cruces de gran tama\u00f1o no que hoxe co\u00f1ecemos como Rosal\u00eda de Castro.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-390fb07 elementor-widget elementor-widget-image\" data-id=\"390fb07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Plano de Vigo de Manuel Cominges 1946\" data-elementor-lightbox-description=\"Plano de Vigo de Manuel Cominges 1946\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzg1MCwidXJsIjoiaHR0cHM6XC9cL2ZvcnRhbGV6YWRlb2Nhc3Ryby52aWdvLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDJcLzA4X3BsYW5vX2NvbWluZ2VzLXNjYWxlZC5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-1024x676.jpg\" class=\"attachment-large size-large wp-image-7850\" alt=\"\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-1024x676.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-300x198.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-768x507.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-1536x1014.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-2048x1352.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-415x274.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-650x429.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-250x165.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/08_plano_cominges-600x396.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Plano de Vigo de Manuel Cominges 1946<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f92e585 elementor-widget elementor-widget-image\" data-id=\"f92e585\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Gran V\u00eda ao pouco de ser trazada\" data-elementor-lightbox-description=\"Gran V\u00eda ao pouco de ser trazada\n\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzg0NiwidXJsIjoiaHR0cHM6XC9cL2ZvcnRhbGV6YWRlb2Nhc3Ryby52aWdvLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDJcL2xhLWdyYW4tdmMzYWRhLWFsLXBvY28tdGllbXBvLWRlLXNlci10cmF6YWRhLmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"505\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada.jpg\" class=\"attachment-large size-large wp-image-7846\" alt=\"\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada.jpg 800w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada-300x189.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada-768x485.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada-415x262.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada-650x410.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada-250x158.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/la-gran-vc3ada-al-poco-tiempo-de-ser-trazada-600x379.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Gran V\u00eda ao pouco de ser trazada\n<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-715ff34 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"715ff34\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-52d75e4\" data-id=\"52d75e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73f9d7b elementor-widget elementor-widget-heading\" data-id=\"73f9d7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A R\u00eda<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0093b89 elementor-widget elementor-widget-text-editor\" data-id=\"0093b89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Toda paisaxe \u00e9 un produto constru\u00eddo. Unha paisaxe est\u00e1 definida\u00a0 por elementos xeol\u00f3xicos, biol\u00f3xicos e antr\u00f3picos. As formas alombadas que presentan os cumes da maior parte das serras galegas f\u00e1lannos, en termos xeol\u00f3xicos, dunha paisaxe vella. A medida que o home act\u00faa sobre un territorio, este vaise desnaturalizando e na paisaxe adquiren protagonismo os factores antr\u00f3picos. Falamos as\u00ed dunha paisaxe cultural ou humanizada (as paisaxes agrarias son un bo exemplo). Tam\u00e9n acontece no caso da R\u00eda de Vigo, un espazo litoral que presenta un alto grao de humanizaci\u00f3n.<\/span><\/p><p><span style=\"font-weight: 400;\">R\u00eda \u00e9 unha palabra galega que hoxe est\u00e1 presente na linguaxe xeogr\u00e1fica internacional, e que de xeito xen\u00e9rico define aqueles vales fluviais invadidos polo mar en diferentes \u00e9pocas.<\/span><\/p><p><span style=\"font-weight: 400;\">A R\u00eda de Vigo conforma unha unidade xeogr\u00e1fica ben definida. A caracterizaci\u00f3n actual da r\u00eda \u00e9 froito do desenvolvemento de diversas fases. Na s\u00faa morfox\u00e9nese intervi\u00f1eron factores de orde litol\u00f3xica condicionadas, \u00e1 s\u00faa vez, pola tect\u00f3nica.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4cba21 elementor-widget elementor-widget-loquet-image-gallery-widget\" data-id=\"b4cba21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"loquet-image-gallery-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gt-image-gallery gt-style-1\"><div class=\"swiper gt-carousel-container\" data-gt-item=\"1\" data-gt-item-group=\"1\" data-gt-item-space=\"0\" data-gt-loop=\"false\" data-gt-speed=\"1500\" data-gt-centered-slides=\"false\" data-gt-direction=\"horizontal\" data-gt-effect=\"slide\" data-gt-free-mode=\"false\" data-gt-lazy-loading=\"true\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"gt-item\"><div class=\"gt-photo\"><a data-fancybox=\"images\" href=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-scaled.jpg\" data-srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-300x218.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-1024x746.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-768x559.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-1536x1118.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-2048x1491.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-415x302.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-650x473.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-250x182.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-600x437.jpg 600w\" data-caption=\"Fotograf\u00eda de Vigo tomada por Filippo Prosperi en 1895.\"><\/a><div class=\"gt-details\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"feather feather-maximize\"><path d=\"M8 3H5a2 2 0 0 0-2 2v3m18 0V5a2 2 0 0 0-2-2h-3m0 18h3a2 2 0 0 0 2-2v-3M3 16v3a2 2 0 0 0 2 2h3\"><\/path><\/svg><span>Fotograf\u00eda de Vigo tomada por Filippo Prosperi en 1895.<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1864\" src=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Fotograf\u00eda de Vigo tomada por Filippo Prosperi en 1895.\" srcset=\"https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-scaled.jpg 2560w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-300x218.jpg 300w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-1024x746.jpg 1024w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-768x559.jpg 768w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-1536x1118.jpg 1536w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-2048x1491.jpg 2048w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-415x302.jpg 415w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-650x473.jpg 650w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-250x182.jpg 250w, https:\/\/fortalezadeocastro.vigo.org\/wp-content\/uploads\/2024\/02\/Vigo_circa_1895._Fotografia_Filippo_Prosperi-600x437.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af943c7 elementor-widget elementor-widget-text-editor\" data-id=\"af943c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">A estrutura da R\u00eda de Vigo est\u00e1 influenciada por un patr\u00f3n de fracturas que van definir a s\u00faa forma. Hai d\u00faas fracturas que a delimitan polo leste e oeste. A boca da r\u00eda est\u00e1 determinada pola presenza dunha fractura N-S que se prolonga cara ao Sur at\u00e9 A Guarda. A un tempo a Depresi\u00f3n Meridiana, con direcci\u00f3n N-S, vai pechar a cabeceira das r\u00edas na Ensenada de San Sim\u00f3n. O corpo da r\u00eda vaise artellar sobre<\/span><span style=\"font-weight: 400;\"> unha <\/span><span style=\"font-weight: 400;\">fractura, aberta logo da incidencia da oroxenia alpina e que tam\u00e9n significou un reaxustamento entre bloques, que presenta unha direcci\u00f3n NE-SO. Posteriormente asentar\u00e1 sobre esta fractura\u00a0 aberta o complexo fluvial. Outro factor destac\u00e1bel na s\u00faa estruturaci\u00f3n van ser as subidas e descensos <\/span><span style=\"font-weight: 400;\">do nivel do <\/span><span style=\"font-weight: 400;\">mar durante as diferentes fases do \u00faltimo per\u00edodo glaciar. Nalg\u00fans momentos o mar <\/span><span style=\"font-weight: 400;\">estaba por detr\u00e1s das C\u00edes, que naquel momento ser\u00edan monta\u00f1as e non illas. Diversos estudos apuntan que o nivel do mar actual ter\u00edase acadado hai uns cinco mil anos.<\/span><\/p><p><span style=\"font-weight: 400;\">Atopamos tam\u00e9n diferenzas morfol\u00f3xicas entre as d\u00faas marxes da r\u00eda. As\u00ed na Pen\u00ednsula do Morrazo as morfolox\u00edas aplanadas existentes entre Cabo Home e Cangas van deixando paso a formas de maiores pendentes cami\u00f1o de Rande. Atopamos cotas como o Faro de Domaio (622 m), Coto Redondo\/Casti\u00f1eiras (536 m). Pequenas fracturas, con direcci\u00f3ns diversas, van condicionar o asentamento de pequenos cursos fluviais no Morrazo.<\/span><\/p><p><span style=\"font-weight: 400;\">Na marxe meridional, as formas aplanadas, con graos de desenvolvemento diferentes, ser\u00e1n menos frecuentes a medida que nos achegamos ao estreito de Rande. A presenza de cursos fluviais vai facilitar a expansi\u00f3n das formas aplanadas cara <\/span><span style=\"font-weight: 400;\">ao interior. \u00c9 o caso do val do Fragoso vinculado \u00e1 presenza do r\u00edo Lagares.<\/span><\/p><p><span style=\"font-weight: 400;\">No caso de Vigo, o seu territorio presenta en termos xeol\u00f3xicos unha diferenciaci\u00f3n entre un dominio gran\u00edtico no sector occidental do concello e a presenza de rochas metam\u00f3rficas no sector m\u00e1is oriental. O marco de confluencia destes dous sectores caracter\u00edzase por certa <\/span><span style=\"font-weight: 400;\">convulsividade <\/span><span style=\"font-weight: 400;\">que motiva a presenza de certas formas elevadas caso da Gu\u00eda e do Castro. A pervivencia destas formas vai vir determinada tam\u00e9n polo factor erosivo. A incidencia da erosi\u00f3n sobre litolox\u00edas diferentes vai resolverse con respostas diferenciadas. Aqueles materiais con menor grao de resistencia ser\u00e1n desmantelados con maior facilidade que os que presenten maior resistencia.<\/span><\/p><p><span style=\"font-weight: 400;\">A presenza das illas C\u00edes na boca da r\u00eda, con altitudes pr\u00f3ximas aos 200 m, vai ter un papel destacado fronte \u00e1s condici\u00f3ns adversas que o mar presenta en certas \u00e9pocas do ano. Este factor conf\u00edrelle \u00e1 r\u00eda caracter\u00edsticas de refuxio natural para a navegaci\u00f3n.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04e0d4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04e0d4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7c4720\" data-id=\"f7c4720\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O monte de O Castro A defensa de Vigo imaxe cabeceira O monte de O Castro en diferentes vistas na 1\u00ba metade do s\u00e9culo XX&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7866","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fortalezadeocastro.vigo.org\/en\/wp-json\/wp\/v2\/pages\/7866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fortalezadeocastro.vigo.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fortalezadeocastro.vigo.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fortalezadeocastro.vigo.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fortalezadeocastro.vigo.org\/en\/wp-json\/wp\/v2\/comments?post=7866"}],"version-history":[{"count":0,"href":"https:\/\/fortalezadeocastro.vigo.org\/en\/wp-json\/wp\/v2\/pages\/7866\/revisions"}],"wp:attachment":[{"href":"https:\/\/fortalezadeocastro.vigo.org\/en\/wp-json\/wp\/v2\/media?parent=7866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}